{"id":789,"count":1,"description":"","link":"https:\/\/chefrepi.com\/magazine\/tag\/%e3%81%9c%e3%82%93%e3%81%96%e3%81%84\/","name":"\u305c\u3093\u3056\u3044","slug":"%e3%81%9c%e3%82%93%e3%81%96%e3%81%84","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/chefrepi.com\/magazine\/wp-json\/wp\/v2\/tags\/789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chefrepi.com\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chefrepi.com\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chefrepi.com\/magazine\/wp-json\/wp\/v2\/posts?tags=789"},{"href":"https:\/\/chefrepi.com\/magazine\/wp-json\/wp\/v2\/pages?tags=789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}